{"id":4366,"date":"2017-10-12T12:45:30","date_gmt":"2017-10-12T10:45:30","guid":{"rendered":"http:\/\/staging.tv2000.it\/docfilm\/?p=4366"},"modified":"2017-10-12T12:45:40","modified_gmt":"2017-10-12T10:45:40","slug":"con-il-vento-nel-petto-vita-di-contardo-ferrini-lunedi-16-ottobre-in-seconda-serata","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/docfilm\/2017\/10\/12\/con-il-vento-nel-petto-vita-di-contardo-ferrini-lunedi-16-ottobre-in-seconda-serata\/","title":{"rendered":"&#8220;Con il Vento nel petto&#8221; &#8211;  Vita di Contardo Ferrini. <br>Luned\u00ec 16 ottobre in seconda serata"},"content":{"rendered":"<h2 style=\"text-align: center;\"><strong><em>&#8220;Con il Vento nel petto&#8221; &#8211;\u00a0<\/em><em>\u00a0Vita di Contardo Ferrini<\/em><\/strong><\/h2>\n<p><a href=\"http:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/10\/image.jpg\"><img decoding=\"async\" class=\"size-full wp-image-4367 aligncenter\" src=\"http:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/10\/image.jpg\" alt=\"\" width=\"368\" height=\"255\" srcset=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/10\/image.jpg 368w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/10\/image-300x208.jpg 300w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/10\/image-39x27.jpg 39w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/10\/image-280x194.jpg 280w\" sizes=\"(max-width: 368px) 100vw, 368px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Per la prima volta viene raccontata in un film documentario la parabola umana, professionale e spirituale del \u00a0Prof.\u00a0 Contardo Ferrini:\u00a0 accademico, giurista, scienziato. Terziario Francescano. Testimone di un autentico umanesimo cristiano. Nato a Milano nel 1859 e morto a Suna di Verbania, sul Lago Maggiore, nel 1902 a soli 43 anni. Dal 1942 il suo cuore \u00e8 custodito in un reliquiario nella chiesa di Santa Lucia di Suna, mentre il suo corpo riposa nella cripta dell\u2019 Universit\u00e0 Cattolica del Sacro Cuore a Milano.<\/p>\n<p>Il film documentario ripercorre\u00a0 tutti i\u00a0 luoghi\u00a0 della vita di Contardo Ferrini, da Milano a Suna di Verbania , passando per le citt\u00e0 di Berlino, di Pavia, di Messina e di Modena. Illustrazioni ne ricostruiscono i momenti pi\u00f9 significativi quali l\u2019infanzia, gli studi, la formazione professionale, l\u2019impegno politico, gli incontri con i suoi maestri \u2026<\/p>\n<p>Un originale\u00a0 contributo viene dagli\u00a0 attori\u00a0 Bruno Furini nel ruolo di Contardo Ferrini e da Stefano Grillo nel ruolo di uno speciale\u00a0 testimone del passato. Accanto alle voci narranti di\u00a0 Massimo Dapporto,\u00a0 di Rosario Tronnolone \u00a0e di Piero Bernacchi si fa largo l\u2019incantevole colonna sonora di Beppe Frattaroli.<\/p>\n<p>La vita di Contardo Ferrini \u00e8 stata caratterizzata dall\u2019amore per la Bellezza del Creato e dalla Verit\u00e0 in Cristo .<\/p>\n<p>Il 14 aprile del 1947 venne beatificato da Papa Pio XII che per l\u2019occasione disse: \u201cIn\u00a0 lui tutto era diafana chiarezza, sicura tranquillit\u00e0, serena letizia dello spirito, sincera dedizione e inalterato amore per la verit\u00e0. Esteriormente sobrio e riservato, com\u2019egli era, l\u2019opera di lui per\u00f2 irradiava l\u2019interna fiamma contenuta nell\u2019uomo, e ha dedicato la sua vita alla ricerca del vero, cercando dietro il nobile volto di ogni scienza terrena sempre l\u2019eterna verit\u00e0 di Dio.<\/p>\n<p>Contardo Ferrini \u00e8 il Patrono delle Universit\u00e0 Cattoliche<\/p>\n<p><em>\u00a0<\/em><em>Regia:\u00a0Alberto Di Giglio<\/em><\/p>\n<p><a href=\"https:\/\/www.conilventonelpetto.it\/\">Per saperne di pi\u00f9 visita il sito<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"&#8220;Con il Vento nel petto&#8221; &#8211;\u00a0\u00a0Vita di Contardo Ferrini &nbsp; Per la prima volta viene raccontata in un film documentario la parabola umana, professionale e spirituale del \u00a0Prof.\u00a0 Contardo Ferrini:\u00a0 accademico, giurista, scienziato. Terziario Francescano. Testimone di un autentico umanesimo cristiano. Nato a Milano nel 1859 e morto a Suna di Verbania, sul Lago Maggiore, [&hellip;]","protected":false},"author":35,"featured_media":4367,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentari"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/10\/image.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/4366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=4366"}],"version-history":[{"count":1,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/4366\/revisions"}],"predecessor-version":[{"id":4368,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/4366\/revisions\/4368"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/4367"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=4366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=4366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=4366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}