{"id":4315,"date":"2017-10-02T14:40:07","date_gmt":"2017-10-02T12:40:07","guid":{"rendered":"http:\/\/staging.tv2000.it\/docfilm\/?p=4315"},"modified":"2017-10-02T14:40:07","modified_gmt":"2017-10-02T12:40:07","slug":"europia-di-fabio-colazzo-sirio-timossi-martedi-3-ottobre-alle-23-20","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/docfilm\/2017\/10\/02\/europia-di-fabio-colazzo-sirio-timossi-martedi-3-ottobre-alle-23-20\/","title":{"rendered":"&#8220;Europia&#8221; di Fabio Colazzo &#038; Sirio Timossi.<br> Marted\u00ec 3 ottobre alle 23.20"},"content":{"rendered":"<p><a href=\"http:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/10\/EUROPIA4.jpg\"><img decoding=\"async\" class=\"size-large wp-image-4319 alignleft\" src=\"http:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/10\/EUROPIA4-1024x573.jpg\" alt=\"\" width=\"640\" height=\"358\" srcset=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/10\/EUROPIA4-1024x573.jpg 1024w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/10\/EUROPIA4-300x168.jpg 300w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/10\/EUROPIA4-768x429.jpg 768w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/10\/EUROPIA4-48x27.jpg 48w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/10\/EUROPIA4-280x157.jpg 280w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/10\/EUROPIA4-650x363.jpg 650w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/10\/EUROPIA4.jpg 1706w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>Dimenticare un paese in guerra, fuggire da un\u2019epidemia, ricongiungersi ai propri cari, iniziare una nuova vita.<br \/>\nTutto questo \u00e8 possibile dentro i confini di Europia. Tutto questo \u00e8 possibile, ma ha un costo elevato.<br \/>\nPu\u00f2 costare la vita.<br \/>\nQuesto documentario \u00e8 fatto delle storie di persone che non rinunciano al sogno.<br \/>\nUomini e donne che lottano e rischiano tutto in un\u2019avventura drammatica fitta di insidie, di sfruttamento e di<br \/>\ningiustizia. \u201cEuropia\u201d si immerge con delicatezza nelle storie e nelle diverse prospettive di chi ha affrontato lo stesso<br \/>\nincredibile viaggio verso approdi incerti, attraverso il deserto, la prigione, la fuga disperata, il mare. Un\u2019odissea da un<br \/>\npaese pericoloso ad un mondo nuovo, diverso altrettanto spietato e repulsivo. Durante il 2015, Zuwara, Ventimiglia e<br \/>\nCalais diventano nodi centrali sulla mappa dei flussi migratori. A partire da luglio 2015 abbiamo vissuto e<br \/>\ndocumentato gli scogli di Ventimiglia, la jungle di Calais e le carceri libiche. Europia racconta, attraverso momenti di<br \/>\nvita e testimonianze dirette, il disorientamento, l\u2019incertezza e le speranze di profughi in viaggio e la solidariet\u00e0 delle<br \/>\npersone accorse in loro sostegno.<br \/>\nWelcome to Europia.<\/p>\n<p>Regia di Fabio Colazzo &amp; Sirio Timossi<\/p>\n","protected":false},"excerpt":{"rendered":"Dimenticare un paese in guerra, fuggire da un\u2019epidemia, ricongiungersi ai propri cari, iniziare una nuova vita. Tutto questo \u00e8 possibile dentro i confini di Europia. Tutto questo \u00e8 possibile, ma ha un costo elevato. Pu\u00f2 costare la vita. Questo documentario \u00e8 fatto delle storie di persone che non rinunciano al sogno. Uomini e donne che [&hellip;]","protected":false},"author":35,"featured_media":4318,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentari"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/10\/EUROPIA3-1024x575.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/4315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=4315"}],"version-history":[{"count":1,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/4315\/revisions"}],"predecessor-version":[{"id":4320,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/4315\/revisions\/4320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/4318"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=4315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=4315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=4315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}