{"id":4185,"date":"2019-02-22T11:00:24","date_gmt":"2019-02-22T10:00:24","guid":{"rendered":"http:\/\/staging.tv2000.it\/docfilm\/?p=4185"},"modified":"2019-02-22T13:16:59","modified_gmt":"2019-02-22T12:16:59","slug":"le-citta-invisibili-sabato-18-e-25-novembre-alle-19-00-ultime-due-puntate","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/docfilm\/2019\/02\/22\/le-citta-invisibili-sabato-18-e-25-novembre-alle-19-00-ultime-due-puntate\/","title":{"rendered":"Le citt\u00e0 invisibili, prima stagione"},"content":{"rendered":"<figure id=\"attachment_7532\" aria-describedby=\"caption-attachment-7532\" style=\"width: 640px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/12\/InvisibleCities_20170424_7630.jpg\"><img decoding=\"async\" class=\"size-large wp-image-7532\" src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/12\/InvisibleCities_20170424_7630-1024x683.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/12\/InvisibleCities_20170424_7630-1024x683.jpg 1024w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/12\/InvisibleCities_20170424_7630-300x200.jpg 300w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/12\/InvisibleCities_20170424_7630-768x512.jpg 768w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/12\/InvisibleCities_20170424_7630-41x27.jpg 41w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/12\/InvisibleCities_20170424_7630-280x187.jpg 280w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2018\/12\/InvisibleCities_20170424_7630-650x433.jpg 650w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><figcaption id=\"caption-attachment-7532\" class=\"wp-caption-text\"><strong>Riace 24 Aprile 2017 &#8211; Photo: Enrico de Divitiis \/ www.enricodedivitiis.it<\/strong><\/figcaption><\/figure>\n<p><strong>Ogni domenica alle 19.00<\/strong> &#8211; Dopo la nuova stagione di <em>Le citt\u00e0 invisibili<\/em> torna a grande richiesta la prima serie, un percorso a ritroso nell&#8217;Italia che accoglie.<\/p>\n<p>Un viaggio in Italia per svelare luoghi, storie e realt\u00e0 di accoglienza e integrazione&nbsp;possibile. Da Riace a Trento, dal Friuli a Roma, passando attraverso Treviso, Padova,&nbsp;Nard\u00f2 e Bologna, emergono cos\u00ec le citt\u00e0 invisibili nascoste dietro il racconto del visibile&nbsp;che invade le cronache dei tg e dei giornali. Un mondo sommerso di esperienze in cui&nbsp;qualcuno ha avuto il coraggio di trasformare la paura in opportunit\u00e0 e l\u2019utopia in realt\u00e0.<\/p>\n<p>Otto documentari da 50 minuti prodotti da MaGa Production con la regia di Massimo&nbsp;Ferrari, <strong>in onda su TV2000 ogni sabato alle 19<\/strong>, per&nbsp;scoprire l\u2019altra faccia del fenomeno migratorio.<\/p>\n<p><strong>1. RIACE<\/strong><\/p>\n<p>In Calabria, a Riace, c\u2019\u00e8 un vero e proprio avamposto della accoglienza civile e della&nbsp;integrazione e interazione tra persone di diverse etnie ormai da pi\u00f9 di dieci anni. Qui si \u00e8&nbsp;innescato un processo virtuoso per cui l\u2019accoglienza conviene a tutti e fa bene anche&nbsp;all\u2019economia del paese. Seguiamo la vita quotidiana di questo che sembra un paese di un&nbsp;altro mondo, grazie alle politiche di accoglienza del sindaco Domenico Lucano.<br \/>\nConsiderato il terzo miglior sindaco del mondo dal \u201cWorld Mayor Prize\u201d ed entrato nella&nbsp;classifica della rivista americana FORTUNE tra le 50 personalit\u00e0 pi\u00f9 influenti del mondo&nbsp;(unico italiano). Gli stranieri sono 400 su 1800 abitanti totali e la maggior parte dei riacesi&nbsp;lavora proprio grazie ai migranti, \u00e8 cos\u00ec che l\u2019 economia della cittadina torna a girare.<br \/>\n<strong>2.TREVISO<\/strong><br \/>\nA Treviso Antonio, professore di Storia e Filosofia al Liceo Classico, ha deciso insieme a&nbsp;sua moglie e ai figli di sperimentare una forma di accoglienza personale: a casa con loro&nbsp;vivono 6 rifugiati africani. \u00c8 il primo caso in Italia&nbsp;che diventa un vero e proprio laboratorio per nuove forme di accoglienza diffusa in famiglia.<\/p>\n<p><strong>3.BOLOGNA<\/strong><br \/>\nA Bologna si incontrano mondi e culture attraverso l\u2019arte del teatro: Pietro, regista della&nbsp;Compagnia Cantieri Meticci, passa giorni e sere a lavorare con un gruppo eterogeneo&nbsp;formato da migranti ospiti nei Centri accoglienza e cittadini italiani. Danze, canti, racconti e&nbsp;centinaia di biciclette trasformate in velieri sfilano fino a Piazza Maggiore.<\/p>\n<p><strong>4.TRENTO<\/strong><br \/>\nRispetto alla quasi totalit\u00e0 delle Regioni, in Trentino la Provincia gestisce autonomamente&nbsp;le pratiche d\u2019accoglienza.&nbsp;I protagonisti di questa storia sono una famiglia di Siriani, ospitata a Trento dopo&nbsp;l\u2019esperimento riuscito dei corridoi umanitari, una ragazza fuggita dal Camerun che&nbsp;frequenta l\u2019universit\u00e0 di Trento dopo le violenze e le sofferenze subite prima di arrivare in&nbsp;Italia; due ragazzi del Mali diventati casari in un importante caseificio di montagna, un&nbsp;panificatore pakistano che lavora presso uno dei locali storici della citt\u00e0.<\/p>\n<p><strong>5.PADOVA&nbsp;<\/strong>A Padova ci sono le Case a Colori in cui turismo sociale ed accoglienza fanno parte di un&nbsp;unico progetto: turisti, migranti e persone in emergenza abitativa coesistono e convivono.&nbsp;Maurizio Trabuio, dopo anni di esperienza nel sociale e nell\u2019accoglienza, \u00e8 l\u2019ideatore di&nbsp;queste strutture ibride cui gli ospiti vengono coinvolti e responsabilizzati. I rifugiati ospiti di&nbsp;Casa a Colori aiutano a ricostruire Dolo e Mira dopo un uragano e, grazie al supporto ed&nbsp;accompagnamento degli operatori sociali, provano ad inserirsi nella realt\u00e0 sociale e&nbsp;lavorativa della provincia.<\/p>\n<p><strong>6.FRIULI<\/strong><br \/>\nSe altrove l\u2019arrivo di migranti \u00e8 sinonimo di allarme sociale, altrettanto non si pu\u00f2 dire di&nbsp;Trieste, dove il calo demografico e il mercato immobiliare in crisi danno una mano al&nbsp;modello dell\u2019\u201caccoglienza diffusa\u201d.<br \/>\nDopo Trieste il nostro viaggio prosegue tre le montagne della Carnia, seguiamo le&nbsp;straordinarie esperienze di accoglienza ai minori a Bosco di Museis, la realt\u00e0 esemplare&nbsp;del Centro Balducci di Don Pierluigi Di Piazza, le nuove pratiche di inserimento lavorativo&nbsp;della Cooperativa Cramars, nell\u2019ottica dell\u2019inclusione sociale e lavorativa e della&nbsp;valorizzazione delle comunit\u00e0 montane a rischio spopolamento.<\/p>\n<p><strong>7.ROMA<\/strong><br \/>\nA Roma in Via Casilina 634 c&#8217;\u00e8 una casa di accoglienza sperimentale ed innovativa&nbsp;per richiedenti asilo e rifugiati che, dopo il primo periodo nei centri d\u2019accoglienza, possono&nbsp;sperimentare un percorso che li conduca ad una vera e propria autonomia.&nbsp;Casa Scalabrini 634 cerca di far fronte proprio all\u2019esigenza di accompagnare i richiedenti&nbsp;asilo nella seconda e terza fase di accoglienza verso un percorso di reale autonomia ed&nbsp;integrazione.<br \/>\nSituata tra i quartieri della periferia romana di Tor Pignattara e Centocelle, Casa&nbsp;Scalabrini 634 \u00e8 un mix di vita autonoma e vita comunitaria, una citt\u00e0 invisibile che, come&nbsp;emerge dalle storie documentate, pu\u00f2 aiutare i suoi abitanti a diventare dei buoni cittadini&nbsp;dopo il periodo di sostegno ed accompagnamento.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>8.LA CITTA\u2019 DEL RISCATTO<\/strong><br \/>\nDue sono le storie di questo documentario, per raccontare la \u201ccitt\u00e0 del riscatto\u201d, quella che&nbsp;unisce la Puglia al Lazio. I protagonisti sono, da una parte, i ragazzi di \u201cSfruttazero\u201d a&nbsp;Nard\u00f2, dall\u2019altra i ragazzi della cooperativa sociale \u201cBarikam\u00e0, sul Lago di Martignano,&nbsp;alle porte di Roma.&nbsp;Si chiama \u201cNetzanet\u201d il progetto pugliese davvero rivoluzionario legato alla salsa di&nbsp;pomodoro: l\u2019idea \u00e8 quella di superare il caporalato e unire italiani e stranieri nella&nbsp;produzione solidale di salsa di pomodoro biologica, a filiera etica, cio\u00e8 nel rispetto di tutti i&nbsp;lavoratori, contro lo sfruttamento.&nbsp;Barikam\u00e0 (che in lingua Bambara\u2019 significa Resistente) \u00e8, invece, una cooperativa che&nbsp;porta avanti un progetto di micro-reddito e consiste nell\u2019inserimento sociale attraverso la&nbsp;produzione e vendita di yogurt ed ortaggi biologici. I fondatori della Cooperativa, tutti&nbsp;africani, dopo essersi ribellati allo sfruttamento nei campi di Rosarno, hanno trovato in&nbsp;questo modo il loro riscatto sociale ed economico.<\/p>\n","protected":false},"excerpt":{"rendered":"Ogni domenica alle 19.00 &#8211; Dopo la nuova stagione di Le citt\u00e0 invisibili torna a grande richiesta la prima serie, un percorso a ritroso nell&#8217;Italia che accoglie. Un viaggio in Italia per svelare luoghi, storie e realt\u00e0 di accoglienza e integrazione&nbsp;possibile. Da Riace a Trento, dal Friuli a Roma, passando attraverso Treviso, Padova,&nbsp;Nard\u00f2 e Bologna, [&hellip;]","protected":false},"author":35,"featured_media":4186,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentari"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/09\/InvisibleCities_20170424_7516-1024x683.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/4185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=4185"}],"version-history":[{"count":11,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/4185\/revisions"}],"predecessor-version":[{"id":7931,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/4185\/revisions\/7931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/4186"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=4185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=4185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=4185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}