{"id":4164,"date":"2017-09-04T15:39:22","date_gmt":"2017-09-04T13:39:22","guid":{"rendered":"http:\/\/staging.tv2000.it\/docfilm\/?p=4164"},"modified":"2017-09-04T16:12:14","modified_gmt":"2017-09-04T14:12:14","slug":"laura-una-vita-straordinaria-giovedi-7-settembre-alle-21-05","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/docfilm\/2017\/09\/04\/laura-una-vita-straordinaria-giovedi-7-settembre-alle-21-05\/","title":{"rendered":"&#8220;Laura, una vita straordinaria&#8221; <br> gioved\u00ec 7 settembre alle 21.05"},"content":{"rendered":"<p><a href=\"http:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/09\/laura-montoya.jpg\"><img decoding=\"async\" class=\"size-full wp-image-4165 alignleft\" src=\"http:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/09\/laura-montoya.jpg\" alt=\"\" width=\"650\" height=\"600\" srcset=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/09\/laura-montoya.jpg 650w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/09\/laura-montoya-300x277.jpg 300w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/09\/laura-montoya-29x27.jpg 29w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/09\/laura-montoya-280x258.jpg 280w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a>Il 12 maggio 2013, Papa Francesco Bergoglio pronuncia davanti a una moltitudine di persone a Roma il nome di Laura Montoya, in quel momento che per la Colombia \u00e8 nata la\u00a0sua prima Santa. Poco si conosce della sua vita e del suo lavoro; molti la percepiscono come una donna al servizio di Dio, ma Laura era molto di pi\u00f9, era una donna che ha combattuto instancabilmente per cambiare la concezione di un paese profondamente egoista e sessista.<\/p>\n<p>Una Colombia devastata dalle guerre civili fa da scenario alla vita di Laura, una giovane donna di umili origini con una grande passione per la vita religiosa. La sua vita raccontata nel documentario in onda su Tv2000 <strong>gioved\u00ec 7 settembre alle 21.05:\u00a0<\/strong> <em><strong>Laura, una vita straordinaria<\/strong><\/em>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"Il 12 maggio 2013, Papa Francesco Bergoglio pronuncia davanti a una moltitudine di persone a Roma il nome di Laura Montoya, in quel momento che per la Colombia \u00e8 nata la\u00a0sua prima Santa. Poco si conosce della sua vita e del suo lavoro; molti la percepiscono come una donna al servizio di Dio, ma Laura [&hellip;]","protected":false},"author":35,"featured_media":4165,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentari"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2017\/09\/laura-montoya.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/4164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=4164"}],"version-history":[{"count":3,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/4164\/revisions"}],"predecessor-version":[{"id":4171,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/4164\/revisions\/4171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/4165"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=4164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=4164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=4164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}