{"id":40801,"date":"2024-09-13T12:30:52","date_gmt":"2024-09-13T10:30:52","guid":{"rendered":"https:\/\/staging.tv2000.it\/docfilm\/?p=40801"},"modified":"2024-08-08T12:14:55","modified_gmt":"2024-08-08T10:14:55","slug":"il-redentore-di-rio","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/docfilm\/2024\/09\/13\/il-redentore-di-rio\/","title":{"rendered":"Il Redentore di Rio"},"content":{"rendered":"<p><strong><a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2023\/03\/redentore.png\"><img decoding=\"async\" class=\"size-full wp-image-40798 alignleft\" src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2023\/03\/redentore.png\" alt=\"\" width=\"870\" height=\"300\" srcset=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2023\/03\/redentore.png 870w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2023\/03\/redentore-300x103.png 300w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2023\/03\/redentore-768x265.png 768w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2023\/03\/redentore-78x27.png 78w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2023\/03\/redentore-280x97.png 280w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2023\/03\/redentore-650x224.png 650w\" sizes=\"(max-width: 870px) 100vw, 870px\" \/><\/a>Il Redentore di Rio<\/strong><br \/>\nRegia di Henri Guereschi<\/p>\n<p>Il Cristo Redentore ha superato i 90 anni. Simbolo universale che va ben oltre la fede cristiana, conquista i cuori di tutto il mondo, avendo al suo fianco presenze illustri ed emblematiche come il Colosseo, la Torre Eiffel o la Statua di Libert\u00e0.<br \/>\nGrandi personalit\u00e0 del mondo sono gi\u00e0 state ai suoi piedi: i papi Giovanni Paolo II e Francesco, Albert Einstein, il principe Carlo e la principessa Diana, il presidente Barack Obama. Anche artisti come Madonna, Rihanna, John Travolta e tanti altri. Ci sono poi le 800.000 persone che la visitano ogni anno, di cui pi\u00f9 della met\u00e0 stranieri.<br \/>\nNel documentario un focus anche sul progettista, lo scultore francese Paolo Landowski, e tante interviste, immagini attuali e immagini d\u2019archivio, in un viaggio attraverso il simbolismo di questo Cristo che oltre ad avere un significato religioso, ha una dimensione umana, sociale e politica.<br \/>\nE poi le storie attorno a questo grande monumento, come quella di Rubens, proprietario del chiosco Paineiras, o della guida Jo\u00e3o Crist\u00f3v\u00e3o, che ha sostenuto la sua famiglia per anni esclusivamente con questa professione.<\/p>\n","protected":false},"excerpt":{"rendered":"Il Redentore di Rio Regia di Henri Guereschi Il Cristo Redentore ha superato i 90 anni. Simbolo universale che va ben oltre la fede cristiana, conquista i cuori di tutto il mondo, avendo al suo fianco presenze illustri ed emblematiche come il Colosseo, la Torre Eiffel o la Statua di Libert\u00e0. Grandi personalit\u00e0 del mondo [&hellip;]","protected":false},"author":35,"featured_media":40803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-40801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentari"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2023\/03\/CRISTO-1-e1678966245218.png","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/40801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=40801"}],"version-history":[{"count":2,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/40801\/revisions"}],"predecessor-version":[{"id":212867,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/40801\/revisions\/212867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/40803"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=40801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=40801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=40801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}