{"id":290,"date":"2016-02-22T11:12:50","date_gmt":"2016-02-22T10:12:50","guid":{"rendered":"http:\/\/staging.tv2000.it\/docfilm\/?p=290"},"modified":"2016-02-25T10:44:43","modified_gmt":"2016-02-25T09:44:43","slug":"2075-il-clima-che-verra-mercoledi-24-febbraio-alle-21-15","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/docfilm\/2016\/02\/22\/2075-il-clima-che-verra-mercoledi-24-febbraio-alle-21-15\/","title":{"rendered":"\u201c2075: Il clima che verr\u00e0\u201d solo su TV2000"},"content":{"rendered":"<p>Il linguaggio della fiction e quello del documentario uniti per denunciare le conseguenze catastrofiche del riscaldamento globale. Nel 2075 tutte le peggiori previsioni sui cambiamenti climatici si sono avverate, con conseguenze spaventose per il pianeta. Lo descrivono le storie di Julia, che lotta per mantenere il vigneto di famiglia; di Idri e Faouzi, in fuga dalla siccit\u00e0 che attanaglia il Sahara del Sud; di Niels, biologo tedesco in viaggio per incontrare un\u2019esperta di biodiversit\u00e0; di Lotte che combatte per l\u2019approvazione di una Carta Internazionale per la Protezione della Terra. Regia di Marion Milne con Nancy Tate, Tantoo Cardinal e Lucie Jeanne.<\/p>\n<div class=\"rgg-container\" data-rgg-id=\"1\">    <div class=\"rgg-imagegrid captions-title captions-effect-none \" data-rgg-id=\"1\">\n                    <a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/02\/IMG_02.jpg\" data-rel=\"rgg\" rel=\"rgg\" title=\"\" class=\"rgg-disabled size-medium rgg-img\" data-src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/02\/IMG_02-300x169.jpg\" data-ratio=\"1.7751479289941\" data-height=\"169\" data-width=\"300\" aria-label=\"\">\n                            <\/a>\n                    <a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/02\/IMG_03.jpg\" data-rel=\"rgg\" rel=\"rgg\" title=\"\" class=\"rgg-disabled size-medium rgg-img\" data-src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/02\/IMG_03-300x169.jpg\" data-ratio=\"1.7751479289941\" data-height=\"169\" data-width=\"300\" aria-label=\"\">\n                            <\/a>\n                    <a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/02\/IMG_09.jpg\" data-rel=\"rgg\" rel=\"rgg\" title=\"\" class=\"rgg-disabled size-medium rgg-img\" data-src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/02\/IMG_09-300x169.jpg\" data-ratio=\"1.7751479289941\" data-height=\"169\" data-width=\"300\" aria-label=\"\">\n                            <\/a>\n                    <a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/02\/IMG_10-1024x576.jpg\" data-rel=\"rgg\" rel=\"rgg\" title=\"\" class=\"rgg-disabled size-medium rgg-img\" data-src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/02\/IMG_10-300x169.jpg\" data-ratio=\"1.7751479289941\" data-height=\"169\" data-width=\"300\" aria-label=\"\">\n                            <\/a>\n                    <a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/02\/IMG_12.jpg\" data-rel=\"rgg\" rel=\"rgg\" title=\"\" class=\"rgg-disabled size-medium rgg-img\" data-src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/02\/IMG_12-300x169.jpg\" data-ratio=\"1.7751479289941\" data-height=\"169\" data-width=\"300\" aria-label=\"\">\n                            <\/a>\n            <\/div>\n<\/div>\n<div class=\"ssba\"><\/div>\n","protected":false},"excerpt":{"rendered":"Il linguaggio della fiction e quello del documentario uniti per denunciare le conseguenze catastrofiche del riscaldamento globale. Nel 2075 tutte le peggiori previsioni sui cambiamenti climatici si sono avverate, con conseguenze spaventose per il pianeta. Lo descrivono le storie di Julia, che lotta per mantenere il vigneto di famiglia; di Idri e Faouzi, in fuga [&hellip;]","protected":false},"author":35,"featured_media":292,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentari"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/02\/IMG_03.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=290"}],"version-history":[{"count":3,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/290\/revisions"}],"predecessor-version":[{"id":318,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/290\/revisions\/318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/292"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}