{"id":2465,"date":"2016-11-24T16:00:26","date_gmt":"2016-11-24T15:00:26","guid":{"rendered":"http:\/\/staging.tv2000.it\/docfilm\/?p=2465"},"modified":"2016-11-24T16:10:37","modified_gmt":"2016-11-24T15:10:37","slug":"appunti-sulla-felicita-il-risveglio-venerdi-25-novembre-alle-19-30","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/docfilm\/2016\/11\/24\/appunti-sulla-felicita-il-risveglio-venerdi-25-novembre-alle-19-30\/","title":{"rendered":"\u201cAppunti sulla felicit\u00e0 &#8211; Il Risveglio&#8221;<br> Venerd\u00ec 25 novembre alle 19.30"},"content":{"rendered":"<p><a href=\"http:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/11\/Pakistan_2_Reinventing-beauty.png\"><img decoding=\"async\" class=\" size-full wp-image-2467 alignleft\" src=\"http:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/11\/Pakistan_2_Reinventing-beauty.png\" alt=\"pakistan_2_reinventing-beauty\" width=\"900\" height=\"506\" srcset=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/11\/Pakistan_2_Reinventing-beauty.png 900w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/11\/Pakistan_2_Reinventing-beauty-300x169.png 300w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/11\/Pakistan_2_Reinventing-beauty-768x432.png 768w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/11\/Pakistan_2_Reinventing-beauty-48x27.png 48w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/11\/Pakistan_2_Reinventing-beauty-280x157.png 280w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/11\/Pakistan_2_Reinventing-beauty-650x365.png 650w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a>In occasione della <strong>Giornata Internazionale della violenza sulle Donne,<\/strong> Tv2000 ha scelto di riprogrammare un capitolo della serie &#8220;Appunti sulla felicit\u00e0&#8221; di Giuseppe Carrieri.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Il Risveglio &#8211; Un racconto dal Pakistan<\/strong><\/em><\/p>\n<p>Musarrat Misbah \u00e8 un\u2019imprenditrice pakistana di 55 anni che dieci anni fa ha creato un saloon molto speciale, attraverso il quale mette a disposizione degli spazi di lavoro per le donne che sono state vittime di attacchi con l\u2019acido. Questi negozi assumono le donne vittime di violenza e offrono dei trattamenti a quelle che, rese irriconoscibili dalle sostanze corrosive, hanno bisogno di ritrovare l\u2019autostima.<\/p>\n<p><strong>Venerd\u00ec 25 novembre alle 19.30<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Guarda il trailer:<\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"Appunti sulla Felicit\u00e0 - Trailer Pakistan\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/g5gM4xiweTs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p><strong>&#8220;Appunti sulla felicit\u00e0&#8221;<\/strong> \u00e8 il pi\u00f9 grande racconto che sia mai stato fatto sul senso della felicit\u00e0, nel mondo, ai tempi d\u2019oggi. Felicit\u00e0, dal punto di vista dell\u2019autore, vuol significare davvero \u201cessere al mondo\u201d. Dal Pakistan alla piccola isola del Vanuatu, dal burka delle donne afghane ai veli delle madri tuareg del campo di Mbera, dalle malate di HIV che recitano per inventarsi un domani a una scuola a Scampia, passando per altri territori e ritratti, questa serie nasce come una piccola Babele, dove il senso della gioia cresce l\u00ec dove proprio questo grande sentimento sembra essere assente, offeso, impossibile.<\/p>\n<p>Attraverso la meraviglia del paesaggio femminile, la felicit\u00e0 si dichiarer\u00e0 nel suo stupore, attraverso otto chiavi di lettura, otto sue distinte modalit\u00e0 di apparizione, ma non si fornir\u00e0 alcun manuale o guida per possibili indicazioni terapeutiche. La felicit\u00e0 non s\u2019insegna n\u00e9 si vede. Quest\u2019atlante di sorrisi insperati \u00e8 solo una proposta di riflessione per i popoli di tutta la terra, per intendere davvero che in fondo le nostre vite, nel bene e nel male, sono uniche e irripetibili.<\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"Appunti sulla Felicit\u00e0 - Trailer\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/qArwiL-KMGU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p><strong>Il regista Giuseppe Carrieri con i suoi sette \u201cAppunti sulla felicit\u00e0\u201d.<\/strong><br \/>\nPiccoli grandi racconti di vita e di coraggio viaggiando dal Tagikistan, alla Mauritania, Pakistan, Malawi, Sri Lanka. Per raccontare un mondo che ci riguarda\u2026<\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"Appunti sulla felicit\u00e0\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/HKau39Ls19E?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"In occasione della Giornata Internazionale della violenza sulle Donne, Tv2000 ha scelto di riprogrammare un capitolo della serie &#8220;Appunti sulla felicit\u00e0&#8221; di Giuseppe Carrieri. &nbsp; Il Risveglio &#8211; Un racconto dal Pakistan Musarrat Misbah \u00e8 un\u2019imprenditrice pakistana di 55 anni che dieci anni fa ha creato un saloon molto speciale, attraverso il quale mette a [&hellip;]","protected":false},"author":35,"featured_media":2467,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[158,163,162,164],"class_list":["post-2465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentari","tag-25-novembre","tag-appunti-sulla-felicita","tag-giornata-internazionale-della-violenza-sulle-donne","tag-pakistan"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/11\/Pakistan_2_Reinventing-beauty.png","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/2465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=2465"}],"version-history":[{"count":2,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/2465\/revisions"}],"predecessor-version":[{"id":2469,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/2465\/revisions\/2469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/2467"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=2465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=2465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=2465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}