{"id":237564,"date":"2024-11-26T09:05:21","date_gmt":"2024-11-26T08:05:21","guid":{"rendered":"https:\/\/staging.tv2000.it\/docfilm\/?p=237564"},"modified":"2024-11-27T12:35:37","modified_gmt":"2024-11-27T11:35:37","slug":"il-sapore-della-liberta","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/docfilm\/2024\/11\/26\/il-sapore-della-liberta\/","title":{"rendered":"Il sapore della liberta&#8217;"},"content":{"rendered":"<div class=\"HeadingWithLink\">\n<h1 class=\"--styled-as-h2\"><a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2024\/10\/LOCANDINA1.png\"><img decoding=\"async\" class=\"wp-image-237565 alignleft\" src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2024\/10\/LOCANDINA1-768x1024.png\" alt=\"\" width=\"386\" height=\"514\" srcset=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2024\/10\/LOCANDINA1-768x1024.png 768w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2024\/10\/LOCANDINA1-225x300.png 225w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2024\/10\/LOCANDINA1-1152x1536.png 1152w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2024\/10\/LOCANDINA1-20x27.png 20w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2024\/10\/LOCANDINA1-280x373.png 280w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2024\/10\/LOCANDINA1-650x867.png 650w, https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2024\/10\/LOCANDINA1.png 1500w\" sizes=\"(max-width: 386px) 100vw, 386px\" \/><\/a>\u2018Il sapore della libert\u00e0\u2019<\/h1>\n<\/div>\n<div class=\"page__html-content\">\n<p><em>Su Tv2000 dal 24 ottobre, il gioved\u00ec in seconda serata<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Dieci detenute protagoniste della docuserie \u2018Il sapore della libert\u00e0 \u2019 in onda su Tv2000 a partire dal 24 ottobre, il gioved\u00ec in seconda serata.<\/p>\n<p>In ogni puntata una donna racconta la sua vita prima del carcere, le motivazioni della sua detenzione, il percorso di rieducazione e reintegrazione all\u2019interno del carcere e infine, qual \u00e8 il suo rapporto con gli affetti lasciati all\u2019esterno.<\/p>\n<p>Alla detenuta protagonista di puntata si alterna una persona fuori dal carcere, che lei vorrebbe rivedere, che racconta come sia cambiato il loro rapporto.<\/p>\n<p>La puntata si conclude con l\u2019incontro tra la detenuta e la persona che desidera rivedere. Si confrontano e rivivono un momento di ordinaria quotidianit\u00e0: consumare un pasto insieme.<\/p>\n<div class=\"rgg-imagegrid captions-title captions-effect-none \" data-rgg-id=\"1\">Ordine programmazione:<\/div>\n<div data-rgg-id=\"1\">\n<p><strong>PT 1 \u2013 LUCIA&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>PT 2 \u2013 EMILIA&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>PT 3 \u2013 ROSARIA&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>PT 4 \u2013 GABRIELLA<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>PT 5 \u2013 ENZA&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>PT 6 \u2013 ZAMIRA&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>PT 7 \u2013 AMELIA&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>PT 8 \u2013 GIOVANNA&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>PT 9 \u2013 JESSICA&nbsp;<\/strong><\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>PT 10 \u2013 FINALE <\/strong><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"\u2018Il sapore della libert\u00e0\u2019 Su Tv2000 dal 24 ottobre, il gioved\u00ec in seconda serata &nbsp; Dieci detenute protagoniste della docuserie \u2018Il sapore della libert\u00e0 \u2019 in onda su Tv2000 a partire dal 24 ottobre, il gioved\u00ec in seconda serata. In ogni puntata una donna racconta la sua vita prima del carcere, le motivazioni della sua [&hellip;]","protected":false},"author":35,"featured_media":237566,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-237564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentari"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2024\/10\/SNEP5-e1728468434891-1024x1024.png","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/237564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=237564"}],"version-history":[{"count":2,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/237564\/revisions"}],"predecessor-version":[{"id":243762,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/237564\/revisions\/243762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/237566"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=237564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=237564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=237564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}