{"id":1846,"date":"2017-09-29T12:00:54","date_gmt":"2017-09-29T10:00:54","guid":{"rendered":"http:\/\/staging.tv2000.it\/docfilm\/?p=1846"},"modified":"2017-10-02T17:33:28","modified_gmt":"2017-10-02T15:33:28","slug":"if-un-documentario-di-nicola-abbatangelo-lunedi-2-ottobre-alle-23-00","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/docfilm\/2017\/09\/29\/if-un-documentario-di-nicola-abbatangelo-lunedi-2-ottobre-alle-23-00\/","title":{"rendered":"&#8220;If&#8221; un documentario di Nicola Abbatangelo. <br>Luned\u00ec 2 ottobre alle 23.00"},"content":{"rendered":"<p>https:\/\/vimeo.com\/169845189<\/p>\n<p>\u201cIf\u201d, \u00e8 un documentario che apre lo sguardo sulla vita reale di famiglie che vivono un quotidiano insolito, sicuramente diverso da quello che si respira, in genere, nelle case di ognuno. Gravi disabilit\u00e0, condizioni invalidanti, la vita che scorre su binari poco battuti. Giulia, Alessandro, Daniela, tre storie che si intrecciano, sfiorandosi in un piano sequenza mai scontato o giudicante. \u201cSe capitasse a me? Se fossi io\u2026..\u201d, \u201cIf\u201d non offre risposte preconfezionate, panacee edulcorate o rassicuranti, ma costringe ognuno a fare i conti con la propria storia, a confrontarsi con le fatiche dei protagonisti, con i loro sorrisi, le lacrime e certezze conquistate. Fotogramma dopo fotogramma, da Bra a Pordenone, sino all\u2019Isola d\u2019Elba, come in un viaggio ulissiaco, \u201cIf\u201d porta in scena quei brandelli di vita che, per paura o pudore, la societ\u00e0 moderna tende a celare o confinare sottotraccia. Non v\u2019\u00e8 spazio per la retorica del dolore o per gli esegeti del politicamente corretto, &#8220;If\u201d pone domande, chiede attenzione, interroga ognuno.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>GALLERY FOTOGRAFICA<\/strong><\/p>\n<div class=\"rgg-container\" data-rgg-id=\"1\">    <div class=\"rgg-imagegrid captions-title captions-effect-none \" data-rgg-id=\"1\">\n                    <a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/1622392_730551483664437_4859805437439945625_o-1024x683.jpg\" data-rel=\"rgg\" rel=\"rgg\" title=\"\" class=\"rgg-disabled size-thumbnail rgg-img\" data-src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/1622392_730551483664437_4859805437439945625_o-150x150.jpg\" data-ratio=\"1\" data-height=\"150\" data-width=\"150\" aria-label=\"\">\n                            <\/a>\n                    <a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/1907829_756317777754474_1984663582522020562_o-1024x269.jpg\" data-rel=\"rgg\" rel=\"rgg\" title=\"\" class=\"rgg-disabled size-thumbnail rgg-img\" data-src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/1907829_756317777754474_1984663582522020562_o-150x150.jpg\" data-ratio=\"1\" data-height=\"150\" data-width=\"150\" aria-label=\"\">\n                            <\/a>\n                    <a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10300520_728170443902541_3982169403161913963_n.jpg\" data-rel=\"rgg\" rel=\"rgg\" title=\"\" class=\"rgg-disabled size-thumbnail rgg-img\" data-src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10300520_728170443902541_3982169403161913963_n-150x150.jpg\" data-ratio=\"1\" data-height=\"150\" data-width=\"150\" aria-label=\"\">\n                            <\/a>\n                    <a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10353273_730552656997653_2761050695964210592_o-1024x683.jpg\" data-rel=\"rgg\" rel=\"rgg\" title=\"\" class=\"rgg-disabled size-thumbnail rgg-img\" data-src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10353273_730552656997653_2761050695964210592_o-150x150.jpg\" data-ratio=\"1\" data-height=\"150\" data-width=\"150\" aria-label=\"\">\n                            <\/a>\n                    <a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10454278_733789923340593_633498880828885746_o-1024x683.jpg\" data-rel=\"rgg\" rel=\"rgg\" title=\"\" class=\"rgg-disabled size-thumbnail rgg-img\" data-src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10454278_733789923340593_633498880828885746_o-150x150.jpg\" data-ratio=\"1\" data-height=\"150\" data-width=\"150\" aria-label=\"\">\n                            <\/a>\n                    <a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10480584_730551793664406_4072045362999082272_o-1024x683.jpg\" data-rel=\"rgg\" rel=\"rgg\" title=\"\" class=\"rgg-disabled size-thumbnail rgg-img\" data-src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10480584_730551793664406_4072045362999082272_o-150x150.jpg\" data-ratio=\"1\" data-height=\"150\" data-width=\"150\" aria-label=\"\">\n                            <\/a>\n                    <a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10480640_733809076672011_2357512903579995888_n.jpg\" data-rel=\"rgg\" rel=\"rgg\" title=\"\" class=\"rgg-disabled size-thumbnail rgg-img\" data-src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10480640_733809076672011_2357512903579995888_n-150x150.jpg\" data-ratio=\"1\" data-height=\"150\" data-width=\"150\" aria-label=\"\">\n                            <\/a>\n                    <a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10498246_730552570330995_8835616323982815551_o-683x1024.jpg\" data-rel=\"rgg\" rel=\"rgg\" title=\"\" class=\"rgg-disabled size-thumbnail rgg-img\" data-src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10498246_730552570330995_8835616323982815551_o-150x150.jpg\" data-ratio=\"1\" data-height=\"150\" data-width=\"150\" aria-label=\"\">\n                            <\/a>\n                    <a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10511663_733790466673872_7054606678597629587_o-1024x683.jpg\" data-rel=\"rgg\" rel=\"rgg\" title=\"\" class=\"rgg-disabled size-thumbnail rgg-img\" data-src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10511663_733790466673872_7054606678597629587_o-150x150.jpg\" data-ratio=\"1\" data-height=\"150\" data-width=\"150\" aria-label=\"\">\n                            <\/a>\n                    <a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10514304_728164477236471_4786752112624019875_o-768x1024.jpg\" data-rel=\"rgg\" rel=\"rgg\" title=\"\" class=\"rgg-disabled size-thumbnail rgg-img\" data-src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10514304_728164477236471_4786752112624019875_o-150x150.jpg\" data-ratio=\"1\" data-height=\"150\" data-width=\"150\" aria-label=\"\">\n                            <\/a>\n                    <a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10531473_733790260007226_3658498882731191788_o-1024x683.jpg\" data-rel=\"rgg\" rel=\"rgg\" title=\"\" class=\"rgg-disabled size-thumbnail rgg-img\" data-src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10531473_733790260007226_3658498882731191788_o-150x150.jpg\" data-ratio=\"1\" data-height=\"150\" data-width=\"150\" aria-label=\"\">\n                            <\/a>\n                    <a href=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10629878_756318061087779_1883893929340724986_n.jpg\" data-rel=\"rgg\" rel=\"rgg\" title=\"\" class=\"rgg-disabled size-thumbnail rgg-img\" data-src=\"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/10629878_756318061087779_1883893929340724986_n-150x150.jpg\" data-ratio=\"1\" data-height=\"150\" data-width=\"150\" aria-label=\"\">\n                            <\/a>\n            <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"https:\/\/vimeo.com\/169845189 \u201cIf\u201d, \u00e8 un documentario che apre lo sguardo sulla vita reale di famiglie che vivono un quotidiano insolito, sicuramente diverso da quello che si respira, in genere, nelle case di ognuno. Gravi disabilit\u00e0, condizioni invalidanti, la vita che scorre su binari poco battuti. Giulia, Alessandro, Daniela, tre storie che si intrecciano, sfiorandosi in un [&hellip;]","protected":false},"author":35,"featured_media":1859,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentari"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/10\/iff-e1475491764578.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/1846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=1846"}],"version-history":[{"count":3,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/1846\/revisions"}],"predecessor-version":[{"id":4306,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/1846\/revisions\/4306"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/1859"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=1846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=1846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=1846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}