{"id":1525,"date":"2016-08-24T11:40:40","date_gmt":"2016-08-24T09:40:40","guid":{"rendered":"http:\/\/staging.tv2000.it\/docfilm\/?p=1525"},"modified":"2016-08-24T11:46:18","modified_gmt":"2016-08-24T09:46:18","slug":"la-madre-dei-poveri-di-pina-cataldo-sabato-3-settembre-alle-20-30-e-domenica-4-settembre-alle-14-25","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/docfilm\/2016\/08\/24\/la-madre-dei-poveri-di-pina-cataldo-sabato-3-settembre-alle-20-30-e-domenica-4-settembre-alle-14-25\/","title":{"rendered":"\u201cLa madre dei poveri\u201d di Pina Cataldo. Sabato 3 settembre alle 20.30 e domenica 4 settembre alle 14.25"},"content":{"rendered":"<p>Il filmato ha la forma del docufilm, ossia solo i testimoni in prima persona sono i protagonisti dello \u201cspeciale\u201d. Costruito, tra l\u2019altro, su testimonianze, interviste, immagini\u00a0 e fotografie inedite \u2013 ripercorre la vita di Madre Teresa di Calcutta attraverso i tratti \u2013 anche nascosti \u2013 della sua personalit\u00e0: dalle origini a Skopje, al periodo trascorso nella citt\u00e0 di Calcutta come insegnante di storia e geografia. Quindi il cosiddetto periodo di \u201coscurit\u00e0\u201d e di travaglio spirituale con la conseguente \u201cchiamata nella chiamata\u201d da cui scaturisce la scelta di dedicare la vita consacrata ai \u201cpi\u00f9 poveri dei poveri\u201d.\u00a0 Da qui i primi difficili anni trascorsi tra i baraccati di Calcutta, la nascita e la diffusione dei Missionari della Carit\u00e0 in tutto il mondo, il premio Nobel, la notoriet\u00e0 ed infine la canonizzazione annunciata da Papa Francesco il 15 marzo 2016 e che verr\u00e0 proclamata santa il 4 settembre prossimo.<\/p>\n","protected":false},"excerpt":{"rendered":"Il filmato ha la forma del docufilm, ossia solo i testimoni in prima persona sono i protagonisti dello \u201cspeciale\u201d. Costruito, tra l\u2019altro, su testimonianze, interviste, immagini\u00a0 e fotografie inedite \u2013 ripercorre la vita di Madre Teresa di Calcutta attraverso i tratti \u2013 anche nascosti \u2013 della sua personalit\u00e0: dalle origini a Skopje, al periodo trascorso [&hellip;]","protected":false},"author":6,"featured_media":1526,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentari"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2016\/08\/madre-teresa-di-calcutta-1006_600x449f.2c662.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/1525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=1525"}],"version-history":[{"count":1,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/1525\/revisions"}],"predecessor-version":[{"id":1527,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/1525\/revisions\/1527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/1526"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=1525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=1525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=1525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}