{"id":11333,"date":"2021-08-31T11:37:10","date_gmt":"2021-08-31T09:37:10","guid":{"rendered":"http:\/\/staging.tv2000.it\/docfilm\/?p=11333"},"modified":"2021-08-31T15:35:46","modified_gmt":"2021-08-31T13:35:46","slug":"ubuntu-io-sono-perche-noi-siamo","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/docfilm\/2021\/08\/31\/ubuntu-io-sono-perche-noi-siamo\/","title":{"rendered":"Ubuntu. Io sono perch\u00e9 noi siamo"},"content":{"rendered":"<p><em>Ubuntu. Io sono perch\u00e9 noi siamo<\/em> di&nbsp;Daniele Palmi, Matteo Morandini<\/p>\n<p><em>Trama<\/em><\/p>\n<p>Nella primavera del 2017 la vita di Poggio alla Croce, piccolo paese in provincia di Firenze, viene turbata dalla notizia dell\u2019arrivo di un gruppo di circa 30 migranti. Fra paura, rabbia e indifferenza, alcuni cittadini cercano di trovare una soluzione e sperimentano originali modalit\u00e0 di integrazione.<br \/>\nUbuntu \u00e8 una filosofia africana che significa che siamo tutti fratelli e se io aiuto te e tu aiuti me viviamo meglio.<\/p>\n<p><strong>RIVEDI<\/strong><\/p>\n<p>https:\/\/youtu.be\/hqv06BoAHoM<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"Ubuntu. Io sono perch\u00e9 noi siamo di&nbsp;Daniele Palmi, Matteo Morandini Trama Nella primavera del 2017 la vita di Poggio alla Croce, piccolo paese in provincia di Firenze, viene turbata dalla notizia dell\u2019arrivo di un gruppo di circa 30 migranti. Fra paura, rabbia e indifferenza, alcuni cittadini cercano di trovare una soluzione e sperimentano originali modalit\u00e0 [&hellip;]","protected":false},"author":35,"featured_media":11359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-11333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-documentari"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/docfilm\/wp-content\/uploads\/sites\/30\/2021\/08\/MANIFESTO-PROVVISORIO-UBUNTU-e1626081703570-939x1024.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/11333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/comments?post=11333"}],"version-history":[{"count":6,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/11333\/revisions"}],"predecessor-version":[{"id":11479,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/posts\/11333\/revisions\/11479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media\/11359"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/media?parent=11333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/categories?post=11333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/docfilm\/wp-json\/wp\/v2\/tags?post=11333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}