{"id":783,"date":"2021-05-16T10:00:22","date_gmt":"2021-05-16T08:00:22","guid":{"rendered":"http:\/\/staging.tv2000.it\/buongiornoprofessore\/?post_type=video&#038;p=783"},"modified":"2021-05-17T09:55:00","modified_gmt":"2021-05-17T07:55:00","slug":"16-maggio-2021-la-speranza","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/video\/16-maggio-2021-la-speranza\/","title":{"rendered":"16 maggio 2021 &#8211; La speranza"},"content":{"rendered":"<p>Gli uomini sono sempre in cammino e man mano che avanzano con l&#8217;et\u00e0 si accorgono di quanto sono imperfetti e capaci di commettere errori. La grande cantica di Dante sul Purgatorio rappresenta ed esplicita il concetto di imperfezione che il prof. Giovanni Ricciardi evidenzia in questa lezione agli studenti del Liceo Classico Pilo Albertelli di Roma partendo proprio dal dolore che si prova verso se stessi o gli altri per una colpa commessa. L&#8217;uomo vive nel tempo ed \u00e8 immerso nel cambiamento che gli consente di tornare indietro e modificare i suoi comportamenti, non continuare a sbagliare, chiedere scusa e non perseverare nell&#8217;errore, capire e tendere verso la perfezione. Il dolore che si prova rispetto a ci\u00f2 che si fa di male \u00e8 gi\u00e0 di per s\u00e9 un fuoco purificatore. Chiedere aiuto \u00e8 un primo passo e forse il Purgatorio \u00e8 il luogo in cui \u00e8 concesso all&#8217;uomo quel tempo in pi\u00f9 che non ha avuto in vita. Solo l&#8217;amore e la misericordia di cui l&#8217;uomo \u00e8 circondato sono la vera speranza, il vero abbraccio in grado di cancellare tutta una vita di errori.<\/p>\n","protected":false},"featured_media":784,"comment_status":"open","ping_status":"closed","template":"","tags":[],"class_list":["post-783","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-puntate-2020-2021"],"acf":[],"aioseo_notices":[],"url_youtube":"-GrhKeCsgaQ","featured_image_url":"https:\/\/i.ytimg.com\/vi\/-GrhKeCsgaQ\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/video\/783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/comments?post=783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/media\/784"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/media?parent=783"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/tags?post=783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}