{"id":778,"date":"2021-05-02T11:35:13","date_gmt":"2021-05-02T09:35:13","guid":{"rendered":"http:\/\/staging.tv2000.it\/buongiornoprofessore\/?post_type=video&#038;p=778"},"modified":"2022-04-27T21:13:20","modified_gmt":"2022-04-27T19:13:20","slug":"2-maggio-2021-linferno-esiste","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/video\/2-maggio-2021-linferno-esiste\/","title":{"rendered":"2 maggio 2021 &#8211; L&#8217;inferno esiste?"},"content":{"rendered":"<p>In questa lezione di Buongiorno Professore Andrea Monda pone alcune domande agli studenti del Liceo Classico Pilo Albertelli di Roma per stuzzicare la loro curiosit\u00e0 e ascoltare le loro considerazioni in merito all&#8217;argomento &#8220;Inferno&#8221;. Per molti l&#8217;inferno \u00e8 qui sulla terra, in questa vita, per tanti non esiste n\u00e9 ora n\u00e9 dopo la morte. Ma quindi esiste o no? E se esiste chi ci va? E soprattutto c&#8217;\u00e8 ancora qualcuno che ci crede? In effetti al giorno d&#8217;oggi sembra un pensiero alquanto superato come superato \u00e8 il concetto di peccato e peccatori. L&#8217;inferno \u00e8 pi\u00f9 che altro una condizione che molti accettano di vivere passivamente lasciandosi trascinare, assolvendosi da soli, spegnendo la propria coscienza critica fino ad assuefarsi al male e allo stato delle cose. Altri invece in modo pi\u00f9 rischioso e faticoso continuano a lottare e sperare credendo che il bene esista e cercando di riconoscerlo e curarlo per farlo durare. L&#8217;inferno ci porta a fare domande sulla qualit\u00e0 della nostra vita e delle nostre relazioni ma, come dice il Papa Emerito Benedetto XVI, l&#8217;inferno \u00e8 legato alla speranza della giustizia e dunque senza inferno non c&#8217;\u00e8 libero arbitrio, non c&#8217;\u00e8 dignit\u00e0 e non c&#8217;\u00e8 giustizia.<\/p>\n","protected":false},"featured_media":779,"comment_status":"open","ping_status":"closed","template":"","tags":[],"class_list":["post-778","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-puntate-2020-2021"],"acf":[],"aioseo_notices":[],"url_youtube":"9nYoK7pM_Bg","featured_image_url":"https:\/\/i.ytimg.com\/vi\/9nYoK7pM_Bg\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/video\/778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/comments?post=778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/media\/779"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/media?parent=778"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/tags?post=778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}