{"id":751,"date":"2021-02-07T21:51:36","date_gmt":"2021-02-07T20:51:36","guid":{"rendered":"http:\/\/staging.tv2000.it\/buongiornoprofessore\/?post_type=video&#038;p=751"},"modified":"2021-02-07T21:51:36","modified_gmt":"2021-02-07T20:51:36","slug":"7-febbraio-2021-linfinito-di-icaro","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/video\/7-febbraio-2021-linfinito-di-icaro\/","title":{"rendered":"7 febbraio 2021 &#8211; L&#8217;infinito di Icaro"},"content":{"rendered":"<p>Per dire qualcosa di profondo e arrivare al cuore delle cose non ci vuole per forza una fredda ragione che analizza tutto punto per punto, ma l&#8217;esercizio della ricerca della verit\u00e0 che \u00e8 pura semplicit\u00e0. Il prof. Giovanni Ricciardi in questa lezione con gli studenti del Liceo Classico Pilo Albertelli di Roma, osservando l&#8217;opera di Matisse &#8220;Icaro&#8221;, spiega il messaggio universale del mito greco e protagonista del quadro: il desiderio di raggiungere l&#8217;infinito. In quanto esseri umani solo l&#8217;unione di cuore e ragione ci consente di librarci in volo nonostante il rischio di cadere.<\/p>\n","protected":false},"featured_media":752,"comment_status":"open","ping_status":"closed","template":"","tags":[],"class_list":["post-751","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-puntate-2020-2021"],"acf":[],"aioseo_notices":[],"url_youtube":"8MnRfmxBZOQ","featured_image_url":"https:\/\/i.ytimg.com\/vi\/8MnRfmxBZOQ\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/video\/751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/comments?post=751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/media\/752"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/media?parent=751"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/tags?post=751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}