{"id":683,"date":"2020-03-30T13:15:15","date_gmt":"2020-03-30T11:15:15","guid":{"rendered":"http:\/\/staging.tv2000.it\/buongiornoprofessore\/?post_type=video&#038;p=683"},"modified":"2020-03-30T13:15:15","modified_gmt":"2020-03-30T11:15:15","slug":"29-marzo-2020-lo-stupore-conosce","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/video\/29-marzo-2020-lo-stupore-conosce\/","title":{"rendered":"29 marzo 2020, &#8220;Lo stupore conosce&#8221;"},"content":{"rendered":"<p>La vita \u00e8 qualcosa da affrontare con le istruzioni per l\u2019uso? Nella lezione di questa domenica a Buongiorno Professore, registrata prima della chiusura delle scuole, Andrea Monda riflette su una breve poesia di Mary Oliver che propone le sue inusuali istruzioni per vivere, tra cui la vigilanza e lo stupore. Se si \u00e8 attenti la vita non pu\u00f2 che sorprendere sempre. Come Lucio Dalla ricorda l\u2019importanza dell\u2019essere pronti: \u201cio mi sto preparando, \u00e8 questa la novit\u00e0\u201d, cos\u00ec Cesare Pavese afferma che nell\u2019apertura alle cose ogni mattina c\u2019\u00e8 la possibilit\u00e0 dell\u2019 \u201cinaudita scoperta\u201d. Con l\u2019aiuto degli studenti del liceo classico \u201cPilo Albertelli\u201d di Roma, si individua il rischio che l\u2019abitudine e la tendenza a chiudersi in se stessi diventino nemici della capacit\u00e0 di sorprendersi e quindi di conoscere le cose. In una frase che campeggia sulla lavagna da inizio lezione, infatti, San Gregorio di Nissa invita a riconoscere che \u201cI concetti creano gli idoli, solo lo stupore conosce\u201d.<\/p>\n","protected":false},"featured_media":684,"comment_status":"open","ping_status":"closed","template":"","tags":[],"class_list":["post-683","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-puntate-2019-2020"],"acf":[],"aioseo_notices":[],"url_youtube":"holVM0wiMEc","featured_image_url":"https:\/\/i.ytimg.com\/vi\/holVM0wiMEc\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/video\/683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/comments?post=683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/media\/684"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/media?parent=683"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/tags?post=683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}