{"id":673,"date":"2020-03-08T12:00:45","date_gmt":"2020-03-08T11:00:45","guid":{"rendered":"http:\/\/staging.tv2000.it\/buongiornoprofessore\/?post_type=video&#038;p=673"},"modified":"2020-03-09T12:01:46","modified_gmt":"2020-03-09T11:01:46","slug":"8-marzo-2020-non-funziono","status":"publish","type":"video","link":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/video\/8-marzo-2020-non-funziono\/","title":{"rendered":"8 marzo 2020, \u201cNon funziono\u201d"},"content":{"rendered":"<p>Le cose della vita devono sempre funzionare? Le macchine hanno lo scopo di funzionare e di risolvere i problemi ma \u201cnon potranno mai porne uno\u201d, ricorda Einstein. Nella lezione di questa domenica a Buongiorno Professore, registrata prima del provvedimento di chiusura delle scuole, Il prof. Andrea Monda affronta un nuovo falso comandamento: \u201cBasta che funzioni\u201d. Al contrario delle macchine e degli oggetti, i cui nomi derivano spesso proprio dalla loro funzione, il valore dell\u2019uomo non si pu\u00f2 ridurre alla sua efficienza. Attraverso l\u2019Evangelium Vitae di S.Giovanni Paolo II e gli esempi di alcuni santi moderni, si riflette sul concetto di dignit\u00e0 umana che non pu\u00f2 mai essere calpestata. Grazie ai numerosi spunti offerti, i ragazzi del liceo classico Pilo Albertelli di Roma concordano che la vita non \u00e8 un problema da risolvere quando si inceppa, ma un Mistero bellissimo e drammatico da provare semmai a decifrare.<\/p>\n","protected":false},"featured_media":674,"comment_status":"open","ping_status":"closed","template":"","tags":[],"class_list":["post-673","video","type-video","status-publish","has-post-thumbnail","hentry","video_category-puntate-2019-2020"],"acf":[],"aioseo_notices":[],"url_youtube":"ne8UoGGQA98","featured_image_url":"https:\/\/i.ytimg.com\/vi\/ne8UoGGQA98\/mqdefault.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/video\/673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/types\/video"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/comments?post=673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/media\/674"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/media?parent=673"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/tags?post=673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}