{"id":1054,"date":"2022-12-18T12:21:40","date_gmt":"2022-12-18T11:21:40","guid":{"rendered":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/?p=1054"},"modified":"2022-12-19T12:22:28","modified_gmt":"2022-12-19T11:22:28","slug":"la-paura-del-futuro","status":"publish","type":"post","link":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/2022\/12\/18\/la-paura-del-futuro\/","title":{"rendered":"&#8220;La paura del futuro&#8221;"},"content":{"rendered":"<p>Attesa e timore: C\u2019\u00e8 pi\u00f9 paura o pi\u00f9 speranza del futuro? Perch\u00e9 percepiamo lo scorrere del tempo come una minaccia? Nell\u2019ultima settimana d\u2019avvento, in attesa del Natale, la puntata di fine anno di Buongiorno Professore riflette sul tema del FUTURO partendo dal mito di Tiresia, l\u2019indovino cieco che predice il destino a Ulisse ponendogli una clausola che gli preclude o gli apre due sorti diverse. Il futuro \u00e8 enigma e libert\u00e0 che ci consente di giocare le nostre carte. Possiamo guardare in avanti avendo nostalgia del passato e vivere il presente nella speranza che arrivi qualcosa di bello. Ma l\u2019unico istante davvero pieno \u00e8 il presente: l\u2019hic et nunc come certezza di un\u2019attesa che render\u00e0 sazia la nostra vita. Al mouse, non in cattedra, il professor Giovanni Ricciardi, docente di greco e latino, coi suoi studenti del Liceo Classico Pilo Albertelli di Roma. Questa settimana l\u2019ospite \u00e8 Amedeo Balbi, astrofisico, divulgatore scientifico, docente all\u2019universit\u00e0 di Tor vergata, con il quale si riflette sull\u2019idea di caos e di caso. Cosa aspettarci dal futuro? L\u2019uomo \u00e8 artefice del proprio destino? La scienza pu\u00f2 prevedere? Sotto la protezione della stella cometa, Buongiorno Professore vi augura un buon Natale e un sereno anno nuovo.<\/p>\n<div class=\"fluid-embed-container\"><iframe title=\"Buongiorno Professore (TV2000), 18 dicembre 2022 - &quot;La paura del futuro&quot;\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/i2TSjfeofe0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"Attesa e timore: C\u2019\u00e8 pi\u00f9 paura o pi\u00f9 speranza del futuro? Perch\u00e9 percepiamo lo scorrere del tempo come una minaccia? Nell\u2019ultima settimana d\u2019avvento, in attesa del Natale, la puntata di fine anno di Buongiorno Professore riflette sul tema del FUTURO partendo dal mito di Tiresia, l\u2019indovino cieco che predice il destino a Ulisse ponendogli una [&hellip;]","protected":false},"author":6,"featured_media":1055,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puntate-2022-2023"],"acf":[],"aioseo_notices":[],"featured_image_url":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-content\/uploads\/sites\/27\/2022\/12\/buongiorno-professore-18-dicembre-2022-1024x576.jpg","_links":{"self":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/posts\/1054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/comments?post=1054"}],"version-history":[{"count":1,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/posts\/1054\/revisions"}],"predecessor-version":[{"id":1056,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/posts\/1054\/revisions\/1056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/media\/1055"}],"wp:attachment":[{"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/media?parent=1054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/categories?post=1054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.tv2000.it\/buongiornoprofessore\/wp-json\/wp\/v2\/tags?post=1054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}